{"id":6519,"date":"2023-10-09T08:34:34","date_gmt":"2023-10-09T08:34:34","guid":{"rendered":"https:\/\/viherma.com\/?post_type=product&#038;p=6519"},"modified":"2026-05-28T10:43:28","modified_gmt":"2026-05-28T10:43:28","slug":"barniz-incoloro-satinado-al-agua-promade","status":"publish","type":"product","link":"https:\/\/viherma.com\/index.php\/producto\/barniz-incoloro-satinado-al-agua-promade\/","title":{"rendered":"Barniz Incoloro Satinado al agua Promade"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p>Barniz Incoloro al agua para todo tipo de muebles y maderas de interior que requieran un acabado fino, satinado y sedoso. Con una buena resistencia al rayado y agentes de limpieza.<\/p>\n<p>Cantidad: 750 ml<\/p>\n<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-d3ce9d5\" data-id=\"d3ce9d5\" data-element_type=\"column\">\n<div class=\"elementor-widget-wrap elementor-element-populated\">\n<div class=\"elementor-element elementor-element-91f2ef5 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"91f2ef5\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n<div class=\"elementor-widget-container\">\n<p><span class=\"elementor-icon-list-text\">Muy resistente al rayado y a los agentes de limpieza.<\/span><\/p>\n<p><i class=\"fas fa-square-full\" aria-hidden=\"true\"><\/i><span class=\"elementor-icon-list-text\">Secado r\u00e1pido<\/span><\/p>\n<p><i class=\"fas fa-square-full\" aria-hidden=\"true\"><\/i><span class=\"elementor-icon-list-text\">Protege la madera realzando su veta natural.<\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-979b037\" data-id=\"979b037\" data-element_type=\"column\">\n<div class=\"elementor-widget-wrap elementor-element-populated\">\n<div class=\"elementor-element elementor-element-05f9c7e elementor-align-left elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"05f9c7e\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n<div class=\"elementor-widget-container\">\n<p><span class=\"elementor-icon-list-text\">Sin olor.<\/span><\/p>\n<\/div>\n<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-d3ce9d5\" data-id=\"d3ce9d5\" data-element_type=\"column\">\n<div class=\"elementor-widget-wrap elementor-element-populated\">\n<div class=\"elementor-element elementor-element-91f2ef5 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"91f2ef5\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n<div class=\"elementor-widget-container\">\n<p><strong style=\"font-size: 16px;\">Modo de Empleo<\/strong><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p><main id=\"content\" class=\"site-main post-2099 page type-page status-publish hentry\" role=\"main\"><\/p>\n<div class=\"page-content\">\n<div class=\"elementor elementor-2099\" data-elementor-type=\"wp-page\" data-elementor-id=\"2099\">\n<section class=\"elementor-section elementor-top-section elementor-element elementor-element-73bcd11 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"73bcd11\" data-element_type=\"section\">\n<div class=\"elementor-container elementor-column-gap-default\">\n<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b52af7a\" data-id=\"b52af7a\" data-element_type=\"column\">\n<div class=\"elementor-widget-wrap elementor-element-populated\">\n<div class=\"elementor-element elementor-element-bbfe53a elementor-widget elementor-widget-toggle\" data-id=\"bbfe53a\" data-element_type=\"widget\" data-widget_type=\"toggle.default\">\n<div class=\"elementor-widget-container\">\n<div class=\"elementor-toggle\" role=\"tablist\">\n<div class=\"elementor-toggle-item\">\n<div id=\"elementor-tab-content-1972\" class=\"elementor-tab-content elementor-clearfix elementor-active\" role=\"tabpanel\" data-tab=\"2\" aria-labelledby=\"elementor-tab-title-1972\">\n<p>Remover el contenido del envase y esperar uno o dos minutos. La superficie tiene que estar limpia, seca y sin restos de barnices o ceras. Se recomienda aplicar entre 5\u00baC y 35\u00baC y con una humedad inferior a 70%.\u00a0 Se puede usar con brocha, pistola o rodillo.<\/p>\n<p><strong>Maderas Nuevas:<\/strong>\u00a0Aplicar una o dos manos de\u00a0tapaporos al agua, dependiendo de la porosidad de la madera, lijando previamente cada capa con taco de lija fino. Posteriormente, aplicar una o dos capas del Barniz Satinado Incoloro al Agua. Tambi\u00e9n puede aplicarse directamente el Barniz Satinado como fondo y acabado.<\/p>\n<p><strong>Maderas barnizadas:<\/strong>\u00a0Si el barniz estuviese bien adherido, lijar suavemente y aplicar el producto. Si en cambio, estuviese cuarteado o mal adherido, eliminarlo mediante lijado o decapado hasta llegar a la madera. Eliminar el polvo, etc. y tratarlo como madera nueva.<\/p>\n<p>Se recomienda hacer una prueba aplicando primero una peque\u00f1a cantidad en una zona poco visible para comprobar la compatibilidad del producto con la superficie a tratar.<\/p>\n<p>Las propiedades de este producto pueden variar seg\u00fan el tipo de madera a tratar, la forma de aplicaci\u00f3n o las condiciones de exposici\u00f3n.<\/p>\n<p>Conservar el envase en condiciones adecuadas al resguardo de heladas, altas temperaturas o luz solar directa.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n<\/div>\n<div class=\"post-tags\"><\/div>\n<\/div>\n<section id=\"comments\" class=\"comments-area\"><\/section>\n<p><\/main><\/p>\n<footer class=\"elementor elementor-141 elementor-location-footer\" data-elementor-type=\"footer\" data-elementor-id=\"141\">\n<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1d8bba50 elementor-section-full_width elementor-section-height-min-height elementor-section-height-default elementor-section-items-middle\" data-id=\"1d8bba50\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n<div class=\"elementor-container elementor-column-gap-default\">\n<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1ce7bdf9\" data-id=\"1ce7bdf9\" data-element_type=\"column\">\n<div class=\"elementor-widget-wrap elementor-element-populated\">\n<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2b4a757e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2b4a757e\" data-element_type=\"section\">\n<div class=\"elementor-container elementor-column-gap-default\">\n<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-145496ab\" data-id=\"145496ab\" data-element_type=\"column\">\n<div class=\"elementor-widget-wrap elementor-element-populated\">\n<div class=\"elementor-element elementor-element-23016e3 elementor-widget elementor-widget-theme-site-logo elementor-widget-image\" data-id=\"23016e3\" data-element_type=\"widget\" data-widget_type=\"theme-site-logo.default\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n<\/footer>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Barniz Incoloro al agua para todo tipo de muebles y maderas de interior que requieran un acabado fino, satinado y sedoso. Con una buena resistencia al rayado y agentes de limpieza.<\/p>\n<p>Cantidad: 750 ml<\/p>\n<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-d3ce9d5\" data-id=\"d3ce9d5\" data-element_type=\"column\">\n<div class=\"elementor-widget-wrap elementor-element-populated\">\n<div class=\"elementor-element elementor-element-91f2ef5 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"91f2ef5\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n<div class=\"elementor-widget-container\">\n<p><span class=\"elementor-icon-list-text\">Muy resistente al rayado y a los agentes de limpieza.<\/span><\/p>\n<p><i class=\"fas fa-square-full\" aria-hidden=\"true\"><\/i><span class=\"elementor-icon-list-text\">Secado r\u00e1pido<\/span><\/p>\n<p><i class=\"fas fa-square-full\" aria-hidden=\"true\"><\/i><span class=\"elementor-icon-list-text\">Protege la madera realzando su veta natural.<\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-979b037\" data-id=\"979b037\" data-element_type=\"column\">\n<div class=\"elementor-widget-wrap elementor-element-populated\">\n<div class=\"elementor-element elementor-element-05f9c7e elementor-align-left elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"05f9c7e\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n<div class=\"elementor-widget-container\">\n<p><span class=\"elementor-icon-list-text\">Sin olor.<\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"featured_media":6518,"comment_status":"open","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set"},"product_cat":[15,50,52],"product_tag":[],"class_list":["post-6519","product","type-product","status-publish","has-post-thumbnail","hentry","product_cat-todos-productos","product_cat-productos-para-madera","product_cat-barnices-y-ceras","product_shipping_class-recogida-tienda","desktop-align-center","tablet-align-center","mobile-align-center"],"_links":{"self":[{"href":"https:\/\/viherma.com\/index.php\/wp-json\/wp\/v2\/product\/6519","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/viherma.com\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/viherma.com\/index.php\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/viherma.com\/index.php\/wp-json\/wp\/v2\/comments?post=6519"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/viherma.com\/index.php\/wp-json\/wp\/v2\/media\/6518"}],"wp:attachment":[{"href":"https:\/\/viherma.com\/index.php\/wp-json\/wp\/v2\/media?parent=6519"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/viherma.com\/index.php\/wp-json\/wp\/v2\/product_cat?post=6519"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/viherma.com\/index.php\/wp-json\/wp\/v2\/product_tag?post=6519"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}