{"id":7003,"date":"2023-11-07T09:02:40","date_gmt":"2023-11-07T09:02:40","guid":{"rendered":"https:\/\/viherma.com\/?post_type=product&#038;p=7003"},"modified":"2026-05-28T08:17:08","modified_gmt":"2026-05-28T08:17:08","slug":"cola-blanca-rapida-para-madera-unifix-de-quilosa","status":"publish","type":"product","link":"https:\/\/viherma.com\/index.php\/producto\/cola-blanca-rapida-para-madera-unifix-de-quilosa\/","title":{"rendered":"Cola Blanca R\u00e1pida Para Madera Unifix de Quilosa"},"content":{"rendered":"<p>Cola Blanca R\u00e1pida Para Madera Unifix de Quilosa<\/p>\n<div class=\"product-single__content\">Cola blanca de pegado r\u00e1pido de elementos decorativos y de construcci\u00f3n. Pegado de molduras, rodapi\u00e9s, paneles, azulejos, baldosas y yeso. Apto para pegar poliestireno expandido, materiales de aislamiento, madera, yeso, ladrillo, etc. Al menos uno de los materiales debe ser poroso.<\/div>\n<div><\/div>\n<div class=\"product-single__content\">\n<p class=\"product-advantages__title\"><strong>VENTAJAS<\/strong><\/p>\n<ul class=\"product-advantages__list\">\n<li class=\"product-advantages__individual\"><i class=\"fas fa-check\" aria-hidden=\"true\"><\/i>\u00a0Resistencia a la humedad D3<\/li>\n<li class=\"product-advantages__individual\"><i class=\"fas fa-check\" aria-hidden=\"true\"><\/i>\u00a0Pegado r\u00e1pido<\/li>\n<li class=\"product-advantages__individual\"><i class=\"fas fa-check\" aria-hidden=\"true\"><\/i>\u00a0Uniones resistentes y duraderas<\/li>\n<li class=\"product-advantages__individual\"><i class=\"fas fa-check\" aria-hidden=\"true\"><\/i>\u00a0Transparente una vez seca<\/li>\n<\/ul>\n<\/div>\n<div class=\"product-single__downloads__wrapper\">\n<div class=\"product-single__tabs-content__wrapper container\">\n<div id=\"product-tabs-content\" class=\"tab-content product-tabs-content__wrapper\"><\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Cola Blanca R\u00e1pida Para Madera Unifix de Quilosa<\/p>\n<div class=\"product-single__content\">Cola blanca de pegado r\u00e1pido de elementos decorativos y de construcci\u00f3n. Pegado de molduras, rodapi\u00e9s, paneles, azulejos, baldosas y yeso. Apto para pegar poliestireno expandido, materiales de aislamiento, madera, yeso, ladrillo, etc. Al menos uno de los materiales debe ser poroso.<\/div>\n","protected":false},"featured_media":6998,"comment_status":"open","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set"},"product_cat":[15,50,51],"product_tag":[],"class_list":["post-7003","product","type-product","status-publish","has-post-thumbnail","hentry","product_cat-todos-productos","product_cat-productos-para-madera","product_cat-fijacion-de-madera","desktop-align-center","tablet-align-center","mobile-align-center"],"_links":{"self":[{"href":"https:\/\/viherma.com\/index.php\/wp-json\/wp\/v2\/product\/7003","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/viherma.com\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/viherma.com\/index.php\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/viherma.com\/index.php\/wp-json\/wp\/v2\/comments?post=7003"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/viherma.com\/index.php\/wp-json\/wp\/v2\/media\/6998"}],"wp:attachment":[{"href":"https:\/\/viherma.com\/index.php\/wp-json\/wp\/v2\/media?parent=7003"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/viherma.com\/index.php\/wp-json\/wp\/v2\/product_cat?post=7003"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/viherma.com\/index.php\/wp-json\/wp\/v2\/product_tag?post=7003"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}